{"id":42438,"count":1,"description":"","link":"https:\/\/app.applebyme.cn\/cloud\/tag\/%e4%b8%aa%e4%ba%ba%e6%8e%a5%e5%b9%bf%e5%91%8a%e4%b8%8a%e4%bc%a0appstore","name":"\u4e2a\u4eba\u63a5\u5e7f\u544a\u4e0a\u4f20appstore","slug":"%e4%b8%aa%e4%ba%ba%e6%8e%a5%e5%b9%bf%e5%91%8a%e4%b8%8a%e4%bc%a0appstore","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/tags\/42438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/posts?tags=42438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}