{"id":30368,"count":1,"description":"","link":"https:\/\/app.applebyme.cn\/cloud\/tag\/%e4%b8%93%e4%b8%9aapp%e4%bb%a3%e4%b8%8a%e6%9e%b6","name":"\u4e13\u4e1aapp\u4ee3\u4e0a\u67b6","slug":"%e4%b8%93%e4%b8%9aapp%e4%bb%a3%e4%b8%8a%e6%9e%b6","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/tags\/30368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/posts?tags=30368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}