{"id":12048,"count":3,"description":"","link":"https:\/\/app.applebyme.cn\/cloud\/tag\/%e8%8b%b9%e6%9e%9capp-store%e4%b8%8a%e6%9e%b6%e6%8b%92%e7%bb%9d","name":"\u82f9\u679capp store\u4e0a\u67b6\u62d2\u7edd","slug":"%e8%8b%b9%e6%9e%9capp-store%e4%b8%8a%e6%9e%b6%e6%8b%92%e7%bb%9d","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/tags\/12048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/app.applebyme.cn\/cloud\/wp-json\/wp\/v2\/posts?tags=12048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}